{"id":81768,"date":"2026-04-10T09:44:43","date_gmt":"2026-04-10T08:44:43","guid":{"rendered":"https:\/\/aspres-thuir.com\/service\/cupa-bois\/"},"modified":"2026-08-13T03:15:15","modified_gmt":"2026-08-13T01:15:15","slug":"cupa-bois","status":"publish","type":"tsc_service","link":"https:\/\/aspres-thuir.com\/ca\/service\/cupa-bois\/","title":{"rendered":"CUPA BOIS"},"content":{"rendered":"<p>Bois de chauffage, ch\u00eane ou h\u00eatre, livraison toute l&#8217;ann\u00e9e, vente directe au d\u00e9p\u00f4t, sciure gratuite.<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"tsc_cat_service":[1145],"class_list":["post-81768","tsc_service","type-tsc_service","status-publish","hentry","tsc_cat_service-ameublement-et-decoration"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CUPA BOIS - Office de Tourisme Aspres-Thuir<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aspres-thuir.com\/ca\/service\/cupa-bois\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CUPA BOIS - Office de Tourisme Aspres-Thuir\" \/>\n<meta property=\"og:description\" content=\"Bois de chauffage, ch\u00eane ou h\u00eatre, livraison toute l&#8217;ann\u00e9e, vente directe au d\u00e9p\u00f4t, sciure gratuite.\" \/>\n<meta property=\"og:site_name\" content=\"Office de Tourisme Aspres-Thuir\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-13T01:15:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aspres-thuir.com\\\/ca\\\/service\\\/cupa-bois\\\/\",\"url\":\"https:\\\/\\\/aspres-thuir.com\\\/ca\\\/service\\\/cupa-bois\\\/\",\"name\":\"CUPA BOIS - Office de Tourisme Aspres-Thuir\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aspres-thuir.com\\\/ca\\\/#website\"},\"datePublished\":\"2026-04-10T08:44:43+00:00\",\"dateModified\":\"2026-08-13T01:15:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aspres-thuir.com\\\/ca\\\/service\\\/cupa-bois\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aspres-thuir.com\\\/ca\\\/service\\\/cupa-bois\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aspres-thuir.com\\\/ca\\\/service\\\/cupa-bois\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\",\"item\":\"https:\\\/\\\/aspres-thuir.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Services\",\"item\":\"https:\\\/\\\/aspres-thuir.com\\\/ca\\\/service\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CUPA BOIS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aspres-thuir.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/aspres-thuir.com\\\/ca\\\/\",\"name\":\"Office de Tourisme Aspres-Thuir\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aspres-thuir.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CUPA BOIS - Office de Tourisme Aspres-Thuir","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aspres-thuir.com\/ca\/service\/cupa-bois\/","og_locale":"ca_ES","og_type":"article","og_title":"CUPA BOIS - Office de Tourisme Aspres-Thuir","og_description":"Bois de chauffage, ch\u00eane ou h\u00eatre, livraison toute l&#8217;ann\u00e9e, vente directe au d\u00e9p\u00f4t, sciure gratuite.","og_site_name":"Office de Tourisme Aspres-Thuir","article_modified_time":"2026-08-13T01:15:15+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aspres-thuir.com\/ca\/service\/cupa-bois\/","url":"https:\/\/aspres-thuir.com\/ca\/service\/cupa-bois\/","name":"CUPA BOIS - Office de Tourisme Aspres-Thuir","isPartOf":{"@id":"https:\/\/aspres-thuir.com\/ca\/#website"},"datePublished":"2026-04-10T08:44:43+00:00","dateModified":"2026-08-13T01:15:15+00:00","breadcrumb":{"@id":"https:\/\/aspres-thuir.com\/ca\/service\/cupa-bois\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aspres-thuir.com\/ca\/service\/cupa-bois\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/aspres-thuir.com\/ca\/service\/cupa-bois\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"","item":"https:\/\/aspres-thuir.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Services","item":"https:\/\/aspres-thuir.com\/ca\/service\/"},{"@type":"ListItem","position":3,"name":"CUPA BOIS"}]},{"@type":"WebSite","@id":"https:\/\/aspres-thuir.com\/ca\/#website","url":"https:\/\/aspres-thuir.com\/ca\/","name":"Office de Tourisme Aspres-Thuir","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aspres-thuir.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"}]}},"_links":{"self":[{"href":"https:\/\/aspres-thuir.com\/ca\/wp-json\/wp\/v2\/tsc_service\/81768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aspres-thuir.com\/ca\/wp-json\/wp\/v2\/tsc_service"}],"about":[{"href":"https:\/\/aspres-thuir.com\/ca\/wp-json\/wp\/v2\/types\/tsc_service"}],"wp:attachment":[{"href":"https:\/\/aspres-thuir.com\/ca\/wp-json\/wp\/v2\/media?parent=81768"}],"wp:term":[{"taxonomy":"tsc_cat_service","embeddable":true,"href":"https:\/\/aspres-thuir.com\/ca\/wp-json\/wp\/v2\/tsc_cat_service?post=81768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}