{"id":82989,"date":"2026-04-10T09:48:43","date_gmt":"2026-04-10T08:48:43","guid":{"rendered":"https:\/\/aspres-thuir.com\/service\/eglise-de-sainte-colombe-de-la-commanderie\/"},"modified":"2026-04-22T17:30:16","modified_gmt":"2026-04-22T15:30:16","slug":"eglise-de-sainte-colombe-de-la-commanderie","status":"publish","type":"tsc_service","link":"https:\/\/aspres-thuir.com\/ca\/service\/eglise-de-sainte-colombe-de-la-commanderie\/","title":{"rendered":"EGLISE DE SAINTE COLOMBE DE LA COMMANDERIE"},"content":{"rendered":"<p>L\u2019esgl\u00e9sia de Sainte Colombe \u00e9s d\u2019origen rom\u00e0nic. T\u00e9 una sola nau, sota un arc lleugerament trencat. T\u00e9 un absis orientat a un punt semicircular. L&#8217;edifici generalment t\u00e9 \u00e8xit en la mesura que el muntatge es realitza amb cura, les pedres de runes estan ben tallades i disposades. Fou al\u00e7ada als segles XV o XVI amb l&#8217;afegit d&#8217;una passarel\u2022la, particularment visible perqu\u00e8 la seva obra grossera contrasta amb l&#8217;esgl\u00e9sia mateixa. El campanar es va afegir durant els segles XVII i XVIII. L\u2019esgl\u00e9sia encara cont\u00e9 alguns objectes valuosos: Dues est\u00e0tues reliquiaris del segle XVII, una creu reliquiari del segle XVII i un bust del Crist mort del segle XV.<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"tsc_cat_service":[],"class_list":["post-82989","tsc_service","type-tsc_service","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EGLISE DE SAINTE COLOMBE DE LA COMMANDERIE - Office de Tourisme Aspres-Thuir<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aspres-thuir.com\/ca\/service\/eglise-de-sainte-colombe-de-la-commanderie\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EGLISE DE SAINTE COLOMBE DE LA COMMANDERIE - Office de Tourisme Aspres-Thuir\" \/>\n<meta property=\"og:description\" content=\"L\u2019esgl\u00e9sia de Sainte Colombe \u00e9s d\u2019origen rom\u00e0nic. T\u00e9 una sola nau, sota un arc lleugerament trencat. T\u00e9 un absis orientat a un punt semicircular. L&#8217;edifici generalment t\u00e9 \u00e8xit en la mesura que el muntatge es realitza amb cura, les pedres de runes estan ben tallades i disposades. Fou al\u00e7ada als segles XV o XVI amb [&hellip;]\" \/>\n<meta property=\"og:site_name\" content=\"Office de Tourisme Aspres-Thuir\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-22T15:30:16+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aspres-thuir.com\\\/ca\\\/service\\\/eglise-de-sainte-colombe-de-la-commanderie\\\/\",\"url\":\"https:\\\/\\\/aspres-thuir.com\\\/ca\\\/service\\\/eglise-de-sainte-colombe-de-la-commanderie\\\/\",\"name\":\"EGLISE DE SAINTE COLOMBE DE LA COMMANDERIE - Office de Tourisme Aspres-Thuir\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aspres-thuir.com\\\/ca\\\/#website\"},\"datePublished\":\"2026-04-10T08:48:43+00:00\",\"dateModified\":\"2026-04-22T15:30:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aspres-thuir.com\\\/ca\\\/service\\\/eglise-de-sainte-colombe-de-la-commanderie\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aspres-thuir.com\\\/ca\\\/service\\\/eglise-de-sainte-colombe-de-la-commanderie\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aspres-thuir.com\\\/ca\\\/service\\\/eglise-de-sainte-colombe-de-la-commanderie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\",\"item\":\"https:\\\/\\\/aspres-thuir.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Services\",\"item\":\"https:\\\/\\\/aspres-thuir.com\\\/ca\\\/service\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"EGLISE DE SAINTE COLOMBE DE LA COMMANDERIE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aspres-thuir.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/aspres-thuir.com\\\/ca\\\/\",\"name\":\"Office de Tourisme Aspres-Thuir\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aspres-thuir.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EGLISE DE SAINTE COLOMBE DE LA COMMANDERIE - Office de Tourisme Aspres-Thuir","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aspres-thuir.com\/ca\/service\/eglise-de-sainte-colombe-de-la-commanderie\/","og_locale":"ca_ES","og_type":"article","og_title":"EGLISE DE SAINTE COLOMBE DE LA COMMANDERIE - Office de Tourisme Aspres-Thuir","og_description":"L\u2019esgl\u00e9sia de Sainte Colombe \u00e9s d\u2019origen rom\u00e0nic. T\u00e9 una sola nau, sota un arc lleugerament trencat. T\u00e9 un absis orientat a un punt semicircular. L&#8217;edifici generalment t\u00e9 \u00e8xit en la mesura que el muntatge es realitza amb cura, les pedres de runes estan ben tallades i disposades. Fou al\u00e7ada als segles XV o XVI amb [&hellip;]","og_site_name":"Office de Tourisme Aspres-Thuir","article_modified_time":"2026-04-22T15:30:16+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aspres-thuir.com\/ca\/service\/eglise-de-sainte-colombe-de-la-commanderie\/","url":"https:\/\/aspres-thuir.com\/ca\/service\/eglise-de-sainte-colombe-de-la-commanderie\/","name":"EGLISE DE SAINTE COLOMBE DE LA COMMANDERIE - Office de Tourisme Aspres-Thuir","isPartOf":{"@id":"https:\/\/aspres-thuir.com\/ca\/#website"},"datePublished":"2026-04-10T08:48:43+00:00","dateModified":"2026-04-22T15:30:16+00:00","breadcrumb":{"@id":"https:\/\/aspres-thuir.com\/ca\/service\/eglise-de-sainte-colombe-de-la-commanderie\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aspres-thuir.com\/ca\/service\/eglise-de-sainte-colombe-de-la-commanderie\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/aspres-thuir.com\/ca\/service\/eglise-de-sainte-colombe-de-la-commanderie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"","item":"https:\/\/aspres-thuir.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Services","item":"https:\/\/aspres-thuir.com\/ca\/service\/"},{"@type":"ListItem","position":3,"name":"EGLISE DE SAINTE COLOMBE DE LA COMMANDERIE"}]},{"@type":"WebSite","@id":"https:\/\/aspres-thuir.com\/ca\/#website","url":"https:\/\/aspres-thuir.com\/ca\/","name":"Office de Tourisme Aspres-Thuir","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aspres-thuir.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"}]}},"_links":{"self":[{"href":"https:\/\/aspres-thuir.com\/ca\/wp-json\/wp\/v2\/tsc_service\/82989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aspres-thuir.com\/ca\/wp-json\/wp\/v2\/tsc_service"}],"about":[{"href":"https:\/\/aspres-thuir.com\/ca\/wp-json\/wp\/v2\/types\/tsc_service"}],"wp:attachment":[{"href":"https:\/\/aspres-thuir.com\/ca\/wp-json\/wp\/v2\/media?parent=82989"}],"wp:term":[{"taxonomy":"tsc_cat_service","embeddable":true,"href":"https:\/\/aspres-thuir.com\/ca\/wp-json\/wp\/v2\/tsc_cat_service?post=82989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}