{"id":78378,"date":"2026-03-26T13:48:08","date_gmt":"2026-03-26T12:48:08","guid":{"rendered":"https:\/\/aspres-thuir.com\/hebergement\/neria-au-mas-picagnol-4\/"},"modified":"2026-04-22T17:22:37","modified_gmt":"2026-04-22T15:22:37","slug":"neria-au-mas-picagnol-4","status":"publish","type":"tsc_hebergement","link":"https:\/\/aspres-thuir.com\/de\/hebergement\/neria-au-mas-picagnol-4\/","title":{"rendered":"N\u00c9RIA  AU MAS PICAGNOL"},"content":{"rendered":"<p>Im Herzen der Pyr\u00e9n\u00e9es-Orientales, in einer Landschaft aus Garrigue, Weinbergen und Olivenb\u00e4umen, bietet das Mas Picagnol authentische und komfortable Ferienh\u00e4user. <br \/>\nDas vollst\u00e4ndig renovierte Mas hat seinen Charakter und seinen Charme bewahrt und bietet gleichzeitig Elemente guten Komforts f\u00fcr einen Urlaub mit Tapetenwechsel, bei dem an alles f\u00fcr Sie gedacht wurde! Das Landhaus \u00f6ffnet sich zur umgebenden Natur und l\u00e4dt zum Entspannen ein.<\/p>\n<p>Das Landhaus bietet 6 klimatisierte und unabh\u00e4ngige Ferienwohnungen f\u00fcr 4 bis 6 Personen, jede mit gesch\u00fctzter Terrasse, privaten Entspannungsm\u00f6beln, einer gepflegten und individuellen Dekoration und Einrichtung. Es gibt auch einen Gemeinschaftsraum, in dem Gruppen bis zu 30 Personen empfangen werden k\u00f6nnen, z. B. Cousinaden, Freundschafts- oder Familienfeiern.<\/p>\n<p>Ebenerdiges Ferienhaus mit Wohnzimmer mit ausgestatteter K\u00fcche, Badezimmer, WC, 2 Schlafzimmer (1 Bett 140 cm) (2 Betten 80 cm).<br \/>\nGro\u00dfe private Panoramaterrasse von 50 m\u00b2.<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"tsc_cat_hebergement":[],"class_list":["post-78378","tsc_hebergement","type-tsc_hebergement","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>N\u00c9RIA AU MAS PICAGNOL - Office de Tourisme Aspres-Thuir<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aspres-thuir.com\/de\/hebergement\/neria-au-mas-picagnol-4\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"N\u00c9RIA AU MAS PICAGNOL - Office de Tourisme Aspres-Thuir\" \/>\n<meta property=\"og:description\" content=\"Im Herzen der Pyr\u00e9n\u00e9es-Orientales, in einer Landschaft aus Garrigue, Weinbergen und Olivenb\u00e4umen, bietet das Mas Picagnol authentische und komfortable Ferienh\u00e4user. Das vollst\u00e4ndig renovierte Mas hat seinen Charakter und seinen Charme bewahrt und bietet gleichzeitig Elemente guten Komforts f\u00fcr einen Urlaub mit Tapetenwechsel, bei dem an alles f\u00fcr Sie gedacht wurde! Das Landhaus \u00f6ffnet sich zur [&hellip;]\" \/>\n<meta property=\"og:site_name\" content=\"Office de Tourisme Aspres-Thuir\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-22T15:22:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aspres-thuir.com\\\/de\\\/hebergement\\\/neria-au-mas-picagnol-4\\\/\",\"url\":\"https:\\\/\\\/aspres-thuir.com\\\/de\\\/hebergement\\\/neria-au-mas-picagnol-4\\\/\",\"name\":\"N\u00c9RIA AU MAS PICAGNOL - Office de Tourisme Aspres-Thuir\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aspres-thuir.com\\\/de\\\/#website\"},\"datePublished\":\"2026-03-26T12:48:08+00:00\",\"dateModified\":\"2026-04-22T15:22:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aspres-thuir.com\\\/de\\\/hebergement\\\/neria-au-mas-picagnol-4\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aspres-thuir.com\\\/de\\\/hebergement\\\/neria-au-mas-picagnol-4\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aspres-thuir.com\\\/de\\\/hebergement\\\/neria-au-mas-picagnol-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\",\"item\":\"https:\\\/\\\/aspres-thuir.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"H\u00e9bergements\",\"item\":\"https:\\\/\\\/aspres-thuir.com\\\/de\\\/hebergement\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"N\u00c9RIA AU MAS PICAGNOL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aspres-thuir.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/aspres-thuir.com\\\/de\\\/\",\"name\":\"Office de Tourisme Aspres-Thuir\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aspres-thuir.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"N\u00c9RIA AU MAS PICAGNOL - Office de Tourisme Aspres-Thuir","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aspres-thuir.com\/de\/hebergement\/neria-au-mas-picagnol-4\/","og_locale":"de_DE","og_type":"article","og_title":"N\u00c9RIA AU MAS PICAGNOL - Office de Tourisme Aspres-Thuir","og_description":"Im Herzen der Pyr\u00e9n\u00e9es-Orientales, in einer Landschaft aus Garrigue, Weinbergen und Olivenb\u00e4umen, bietet das Mas Picagnol authentische und komfortable Ferienh\u00e4user. Das vollst\u00e4ndig renovierte Mas hat seinen Charakter und seinen Charme bewahrt und bietet gleichzeitig Elemente guten Komforts f\u00fcr einen Urlaub mit Tapetenwechsel, bei dem an alles f\u00fcr Sie gedacht wurde! Das Landhaus \u00f6ffnet sich zur [&hellip;]","og_site_name":"Office de Tourisme Aspres-Thuir","article_modified_time":"2026-04-22T15:22:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aspres-thuir.com\/de\/hebergement\/neria-au-mas-picagnol-4\/","url":"https:\/\/aspres-thuir.com\/de\/hebergement\/neria-au-mas-picagnol-4\/","name":"N\u00c9RIA AU MAS PICAGNOL - Office de Tourisme Aspres-Thuir","isPartOf":{"@id":"https:\/\/aspres-thuir.com\/de\/#website"},"datePublished":"2026-03-26T12:48:08+00:00","dateModified":"2026-04-22T15:22:37+00:00","breadcrumb":{"@id":"https:\/\/aspres-thuir.com\/de\/hebergement\/neria-au-mas-picagnol-4\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aspres-thuir.com\/de\/hebergement\/neria-au-mas-picagnol-4\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/aspres-thuir.com\/de\/hebergement\/neria-au-mas-picagnol-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"","item":"https:\/\/aspres-thuir.com\/de\/"},{"@type":"ListItem","position":2,"name":"H\u00e9bergements","item":"https:\/\/aspres-thuir.com\/de\/hebergement\/"},{"@type":"ListItem","position":3,"name":"N\u00c9RIA AU MAS PICAGNOL"}]},{"@type":"WebSite","@id":"https:\/\/aspres-thuir.com\/de\/#website","url":"https:\/\/aspres-thuir.com\/de\/","name":"Office de Tourisme Aspres-Thuir","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aspres-thuir.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"}]}},"_links":{"self":[{"href":"https:\/\/aspres-thuir.com\/de\/wp-json\/wp\/v2\/tsc_hebergement\/78378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aspres-thuir.com\/de\/wp-json\/wp\/v2\/tsc_hebergement"}],"about":[{"href":"https:\/\/aspres-thuir.com\/de\/wp-json\/wp\/v2\/types\/tsc_hebergement"}],"wp:attachment":[{"href":"https:\/\/aspres-thuir.com\/de\/wp-json\/wp\/v2\/media?parent=78378"}],"wp:term":[{"taxonomy":"tsc_cat_hebergement","embeddable":true,"href":"https:\/\/aspres-thuir.com\/de\/wp-json\/wp\/v2\/tsc_cat_hebergement?post=78378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}